{"id":213548,"date":"2022-03-22T23:15:53","date_gmt":"2022-03-22T22:15:53","guid":{"rendered":"https:\/\/eny.es\/producto\/bota-sicherheit-kappesohle-s3-fragua-plus-t-41-panter\/"},"modified":"2026-07-06T20:53:17","modified_gmt":"2026-07-06T18:53:17","slug":"bota-sicherheit-kappesohle-s3-fragua-plus-t-41-panter","status":"publish","type":"product","link":"https:\/\/eny.es\/de\/produkt\/bota-sicherheit-kappesohle-s3-fragua-plus-t-41-panter\/","title":{"rendered":"BOTA SICHERHEIT KAPPE+SOHLE S3 FRAGUA PLUS T-41 PANTER"},"content":{"rendered":"<p>Sicherheitsstiefel mit Schnallenverschluss, hergestellt aus Materialien mit au\u00dfergew\u00f6hnlicher Widerstandsf\u00e4higkeit und Haltbarkeit. Ergonomische und extra breite Leisten, die eine spezielle Breite und gro\u00dfe Stabilit\u00e4t bieten.<\/p>\n<p>Hochwertiges, hydrophobiertes Naturleder, ausgew\u00e4hlt f\u00fcr seine Qualit\u00e4t, Widerstandsf\u00e4higkeit und Atmungsaktivit\u00e4t.<br \/>\nBesonders verst\u00e4rkte Sohle, antitorsions Design, best\u00e4ndig gegen \u00d6le und Kohlenwasserstoffe, l\u00e4ngere Lebensdauer und Widerstandsf\u00e4higkeit.<br \/>\nNeue Technologie \u201eOPTIMAL SOLE\u201c. Gr\u00f6\u00dfere Leichtigkeit, Stabilit\u00e4t und Nutzung der D\u00e4mpfung beim Auftreten, um den n\u00e4chsten Schritt zu f\u00f6rdern.<br \/>\nPlastikschutzkappe gegen St\u00f6\u00dfe (200J) und durchtrittsichere Textilsohle (1100N), nicht metallisch.<br \/>\nInnensohle aus Latex-Schaum mit spezieller Bel\u00fcftung und sehr bequem.<br \/>\n\u00dcberdimensionierte Au\u00dfenzunge, zus\u00e4tzlicher Schutz gegen Funken.<br \/>\n3M-Reflektoren, hinten und seitlich (innen und au\u00dfen), mit zertifizierter Retroreflexion.<br \/>\n\u00dcberdimensionierter Kn\u00f6chelschutz mit scheuerfesten Polstern.<br \/>\nInnenfutter mit hoher Abriebfestigkeit, das den Schwei\u00df vom Fu\u00df fernh\u00e4lt.<br \/>\nVerschluss durch Schnellverschluss-Schnalle und Innenkordel.<\/p>\n<p>GR\u00d6SSE 41<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sicherheitsstiefel mit Schnallenverschluss, hergestellt aus Materialien mit au\u00dfergew\u00f6hnlicher Widerstandsf\u00e4higkeit und Haltbarkeit. Ergonomische und extra breite Leisten, die eine spezielle Breite<\/p>\n","protected":false},"featured_media":244104,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[4007],"product_cat":[2174],"product_tag":[],"class_list":["post-213548","product","type-product","status-publish","has-post-thumbnail","product_brand-panter","product_cat-sicherheitsschuhe","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/product\/213548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/comments?post=213548"}],"version-history":[{"count":0,"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/product\/213548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/media\/244104"}],"wp:attachment":[{"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/media?parent=213548"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/product_brand?post=213548"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/product_cat?post=213548"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eny.es\/de\/wp-json\/wp\/v2\/product_tag?post=213548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}